{"id":2903,"date":"2019-03-16T14:48:37","date_gmt":"2019-03-16T14:48:37","guid":{"rendered":"https:\/\/www.latamdigitalmarketing.com\/blog\/?p=2903"},"modified":"2019-07-24T23:15:47","modified_gmt":"2019-07-24T23:15:47","slug":"machine-learning","status":"publish","type":"post","link":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/","title":{"rendered":"Machine Learning, el secreto detr\u00e1s de los algoritmos"},"content":{"rendered":"<p>En muchas oportunidades, nos gustar\u00eda predecir el futuro cercano de nuestra empresa, o conocer lo que quieren nuestros clientes; esto es posible con el Machine Learning.<\/p>\n<p>Las empresas deben comprender que la informaci\u00f3n es el mayor recurso que poseen, por lo que las bases de datos son sus recursos m\u00e1s valiosos.<\/p>\n<p>Al conocer la informaci\u00f3n de sus usuarios, se pueden predecir los comportamientos de los consumidores.<\/p>\n<p>Y al detectar esos patrones en la conducta, podemos planificar que medidas se necesitan ejecutar.<\/p>\n<h3>Machine Learning<\/h3>\n<p>Antes pens\u00e1bamos en una Inteligencia Artificial (IA) de robots que solucionaban problemas para los humanos.<\/p>\n<p>Pero hoy en d\u00eda, existe como automatizaci\u00f3n de procesos, y recolecci\u00f3n de data que aplicamos a proyecciones de las empresas.<\/p>\n<blockquote><p>El\u00a0machine learning,\u00a0conocido en espa\u00f1ol como aprendizaje autom\u00e1tico o aprendizaje de m\u00e1quina, naci\u00f3 como una idea ambiciosa de la IA en la d\u00e9cada de los 60. Para ser m\u00e1s exactos, fue\u00a0una subdisciplina de la IA, producto de las ciencias de la computaci\u00f3n y las neurociencias.<\/p>\n<p>Lo que esta rama pretend\u00eda estudiar era el reconocimiento de patrones (en los procesos de ingenier\u00eda, matem\u00e1ticas, computaci\u00f3n, etc.) y el aprendizaje por parte de las computadoras. En los albores de la IA, los investigadores estaban \u00e1vidos por encontrar una forma en la cual las computadoras pudieran aprender \u00fanicamente bas\u00e1ndose en datos.<\/p><\/blockquote>\n<p>Trabajamos el razonamiento probabil\u00edstico, investigaci\u00f3n basada en la estad\u00edstica, recuperaci\u00f3n de informaci\u00f3n, <a href=\"https:\/\/www.latamdigitalmarketing.com\/blog\/neuromarketing-abc\/\">neuromarketing<\/a>.\u00a0Al unir todo esto, se crea un estilo de perfil de nuestros clientes.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2928 size-full\" src=\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_IMG_Inter.jpg\" alt=\"Machine Learning\" width=\"600\" height=\"469\" srcset=\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_IMG_Inter.jpg 600w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_IMG_Inter-150x117.jpg 150w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_IMG_Inter-300x235.jpg 300w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_IMG_Inter-187x146.jpg 187w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_IMG_Inter-50x39.jpg 50w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_IMG_Inter-96x75.jpg 96w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>De esta forma, con IA somos capaces de crear alertas y proyecciones.<\/p>\n<p>Una vez que se reconoce patrones que los usuarios han tenido y que otros van en la misma l\u00ednea.<\/p>\n<p>Hoy en d\u00eda las empresas saben que las decisiones se toman en base a datos.<\/p>\n<p>Es por esto que, mientras mejor sea la informaci\u00f3n, esta ofrecer\u00e1 m\u00e1s valor para realizar la proyecci\u00f3n.<\/p>\n<h3>Netflix, Caso Real de Machine Learning<\/h3>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-2923 size-full\" src=\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix.jpg\" alt=\"Machine Learning Netflix\" width=\"1400\" height=\"700\" srcset=\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix.jpg 1400w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix-150x75.jpg 150w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix-300x150.jpg 300w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix-768x384.jpg 768w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix-1024x512.jpg 1024w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix-260x130.jpg 260w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix-50x25.jpg 50w, https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Netflix-1200x600.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Una vez entendemos que el Machine Learning nace de la inteligencia artificial, y busca crear un efecto en su base de datos, Netflix es un gran ejemplo de esto.<\/p>\n<p>A trav\u00e9s de diferentes algoritmos, as\u00ed como aprendizajes de otros usuarios, este es capaz de predeterminar perfiles.<\/p>\n<p>Es por esto que a veces nos recomienda pel\u00edculas que considera nos gustar\u00e1n, porque otras personas la han visto.<\/p>\n<p>Incluso, en su \u00faltima mejor\u00eda decidi\u00f3 llevarlo a porcentaje, donde nos indica que tan cercano o apr\u00f3ximado es a nuestros gustos.<\/p>\n<p>Es por esto que con Machine Learning, Netflix intenta personalizar tu experiencia, esto basado en tus preferencias y las de personas similares.<\/p>\n<p>El algoritmo aprende las cosas que te gustan, y en base a ello selecciona un flujo de informaci\u00f3n (en este caso pel\u00edculas y series) para mostrar.<\/p>\n<h3>Considera estas ideas para Machine Learning<\/h3>\n<p>Y ahora que conoces que no tienes l\u00edmite para aplicar el ML a diferentes aspectos de tu empresa, te dejamos una serie de ideas que puedes implementar:<\/p>\n<ul>\n<li>Crea una base de datos din\u00e1mica y automatizada con toda la informaci\u00f3n que es relevante de tus clientes si conoces sus preferencias. As\u00ed, cuando visiten tu p\u00e1gina, puedas ofrecerles recomendaciones de productos.<\/li>\n<li>Ofrecer productos como, por ejemplo, la probabilidad de que el comprador busque art\u00edculos de temporada.<\/li>\n<li>El marketing personalizado se basa en un sencillo principio: mientras m\u00e1s se pueda saber sobre el cliente y su comportamiento, mejor se le podr\u00e1 atender y se traducir\u00e1 en m\u00e1s ventas.<\/li>\n<li>Evitar el blanqueo de capitales, Paypal\u00a0tiene herramientas que comparan millones de transacciones y pueden distinguir con precisi\u00f3n entre transacciones leg\u00edtimas y fraudulentas, entre compradores y vendedores.<\/li>\n<\/ul>\n<p>Y si a\u00fan quieres conocer m\u00e1s sobre la IA y el ML, por aqu\u00ed te dejamos un video que nos habla m\u00e1s al respecto:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=VvTYuQPINec\">https:\/\/www.youtube.com\/watch?v=VvTYuQPINec<\/a><\/p>\n<p>Y si el mundo del Machine Learning te ha cautivado tanto como a nosotros, conoce sobre <a href=\"https:\/\/www.latamdigitalmarketing.com\/blog\/categoria\/programmatic-es\/\">programmatic<\/a>.<\/p>\n<p>Como <a href=\"https:\/\/www.latamdigitalmarketing.com\">Agencia de Perfomance<\/a>, trabajamos para llevar tu marca al pr\u00f3ximo nivel. \u00a1Cont\u00e1ctanos!<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;2903&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Machine Learning, el secreto detr\u00e1s de los algoritmos&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>En muchas oportunidades, nos gustar\u00eda predecir el futuro cercano de nuestra empresa, o conocer lo que quieren nuestros clientes; esto es posible con el Machine Learning. Las empresas deben comprender que la informaci\u00f3n es el mayor recurso que poseen, por lo que las bases de datos son sus recursos m\u00e1s valiosos. Al conocer la informaci\u00f3n &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMachine Learning, el secreto detr\u00e1s de los algoritmos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[329,327],"tags":[420,414,418,416,296],"class_list":["post-2903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-automation","category-programmatic-es","tag-algoritmo","tag-machine-learning","tag-machine-learning-mexico","tag-marketing-automation","tag-neuromarketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Machine Learning, el secreto detr\u00e1s de los algoritmos | LDM\u00ae Latam Digital Marketing<\/title>\n<meta name=\"description\" content=\"Machine Learning | La inteligencia artificial aplicada a conocer el comportamiento de los consumidores, conoce el caso de NETFLIX.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Machine Learning, el secreto detr\u00e1s de los algoritmos | LDM\u00ae Latam Digital Marketing\" \/>\n<meta property=\"og:description\" content=\"Machine Learning | La inteligencia artificial aplicada a conocer el comportamiento de los consumidores, conoce el caso de NETFLIX.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\" \/>\n<meta property=\"og:site_name\" content=\"LDM\u00ae Latam Digital Marketing\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Latamdigitalmarketing\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Latamdigitalmarketing\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-16T14:48:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-24T23:15:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alberto Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AgenciaLDM\" \/>\n<meta name=\"twitter:site\" content=\"@AgenciaLDM\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\"},\"author\":{\"name\":\"Alberto Alvarez\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/person\/e3ff719871c6dac0411a0af17149bd4e\"},\"headline\":\"Machine Learning, el secreto detr\u00e1s de los algoritmos\",\"datePublished\":\"2019-03-16T14:48:37+00:00\",\"dateModified\":\"2019-07-24T23:15:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\"},\"wordCount\":705,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png\",\"keywords\":[\"Algoritmo\",\"Machine Learning\",\"Machine Learning Mexico\",\"Marketing Automation\",\"neuromarketing\"],\"articleSection\":[\"Marketing Automation\",\"Programmatic\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\",\"url\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\",\"name\":\"Machine Learning, el secreto detr\u00e1s de los algoritmos | LDM\u00ae Latam Digital Marketing\",\"isPartOf\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png\",\"datePublished\":\"2019-03-16T14:48:37+00:00\",\"dateModified\":\"2019-07-24T23:15:47+00:00\",\"description\":\"Machine Learning | La inteligencia artificial aplicada a conocer el comportamiento de los consumidores, conoce el caso de NETFLIX.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage\",\"url\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png\",\"contentUrl\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png\",\"width\":800,\"height\":1063,\"caption\":\"Machine Learning Technologies\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Machine Learning, el secreto detr\u00e1s de los algoritmos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#website\",\"url\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/\",\"name\":\"LDM\u00ae Latam Digital Marketing\",\"description\":\"Forward Thinking Marketing\",\"publisher\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#organization\",\"name\":\"Latam Digital Marketing\",\"url\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/profile-picture.jpg\",\"contentUrl\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/profile-picture.jpg\",\"width\":811,\"height\":811,\"caption\":\"Latam Digital Marketing\"},\"image\":{\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Latamdigitalmarketing\",\"https:\/\/x.com\/AgenciaLDM\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/person\/e3ff719871c6dac0411a0af17149bd4e\",\"name\":\"Alberto Alvarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/albertoSmall.jpg\",\"contentUrl\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/albertoSmall.jpg\",\"caption\":\"Alberto Alvarez\"},\"description\":\"Luego de trabajar casi una d\u00e9cada en mercadeo en Procter & Gamble, Alberto envisiona el poder del cambio de la era digital y decide enfocarse en desarrollar el mundo del emprendimiento en Latinoam\u00e9rica. En 2012 funda su primer start-up, gogetit.com.pa, cambiando la forma de interactuar con bienes ra\u00edces en la regi\u00f3n. Alberto, sirvi\u00f3 como VP de Mercadeo de Agora Technologies en Silicon Valley, compa\u00f1\u00eda financiada por Guy Kawasaki & Nolan Bushnell y desarroll\u00f3 el concepto global de Startup Icon. Hoy, Alberto es el CEO del holding de compa\u00f1\u00edas que conforman Latam Digital Marketing, Gogetit y sus subsidiarias en Latinoam\u00e9rica.\",\"sameAs\":[\"https:\/\/www.facebook.com\/Latamdigitalmarketing\/\",\"http:\/\/linkedin.com\/in\/albertoalvarezm\",\"https:\/\/x.com\/AgenciaLDM\"],\"url\":\"https:\/\/www.latamdigitalmarketing.com\/blog\/bio\/alberto-alvarez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Machine Learning, el secreto detr\u00e1s de los algoritmos | LDM\u00ae Latam Digital Marketing","description":"Machine Learning | La inteligencia artificial aplicada a conocer el comportamiento de los consumidores, conoce el caso de NETFLIX.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/","og_locale":"es_ES","og_type":"article","og_title":"Machine Learning, el secreto detr\u00e1s de los algoritmos | LDM\u00ae Latam Digital Marketing","og_description":"Machine Learning | La inteligencia artificial aplicada a conocer el comportamiento de los consumidores, conoce el caso de NETFLIX.","og_url":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/","og_site_name":"LDM\u00ae Latam Digital Marketing","article_publisher":"https:\/\/www.facebook.com\/Latamdigitalmarketing","article_author":"https:\/\/www.facebook.com\/Latamdigitalmarketing\/","article_published_time":"2019-03-16T14:48:37+00:00","article_modified_time":"2019-07-24T23:15:47+00:00","og_image":[{"width":800,"height":1063,"url":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png","type":"image\/png"}],"author":"Alberto Alvarez","twitter_card":"summary_large_image","twitter_creator":"@AgenciaLDM","twitter_site":"@AgenciaLDM","twitter_misc":{"Escrito por":"Alberto Alvarez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#article","isPartOf":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/"},"author":{"name":"Alberto Alvarez","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/person\/e3ff719871c6dac0411a0af17149bd4e"},"headline":"Machine Learning, el secreto detr\u00e1s de los algoritmos","datePublished":"2019-03-16T14:48:37+00:00","dateModified":"2019-07-24T23:15:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/"},"wordCount":705,"commentCount":0,"publisher":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage"},"thumbnailUrl":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png","keywords":["Algoritmo","Machine Learning","Machine Learning Mexico","Marketing Automation","neuromarketing"],"articleSection":["Marketing Automation","Programmatic"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/","url":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/","name":"Machine Learning, el secreto detr\u00e1s de los algoritmos | LDM\u00ae Latam Digital Marketing","isPartOf":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage"},"image":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage"},"thumbnailUrl":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png","datePublished":"2019-03-16T14:48:37+00:00","dateModified":"2019-07-24T23:15:47+00:00","description":"Machine Learning | La inteligencia artificial aplicada a conocer el comportamiento de los consumidores, conoce el caso de NETFLIX.","breadcrumb":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#primaryimage","url":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png","contentUrl":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2019\/03\/Blog_800X1063_Machine_learning.png","width":800,"height":1063,"caption":"Machine Learning Technologies"},{"@type":"BreadcrumbList","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/machine-learning\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.latamdigitalmarketing.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Machine Learning, el secreto detr\u00e1s de los algoritmos"}]},{"@type":"WebSite","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#website","url":"https:\/\/www.latamdigitalmarketing.com\/blog\/","name":"LDM\u00ae Latam Digital Marketing","description":"Forward Thinking Marketing","publisher":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.latamdigitalmarketing.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#organization","name":"Latam Digital Marketing","url":"https:\/\/www.latamdigitalmarketing.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/profile-picture.jpg","contentUrl":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/profile-picture.jpg","width":811,"height":811,"caption":"Latam Digital Marketing"},"image":{"@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Latamdigitalmarketing","https:\/\/x.com\/AgenciaLDM"]},{"@type":"Person","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/person\/e3ff719871c6dac0411a0af17149bd4e","name":"Alberto Alvarez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.latamdigitalmarketing.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/albertoSmall.jpg","contentUrl":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-content\/uploads\/2018\/08\/albertoSmall.jpg","caption":"Alberto Alvarez"},"description":"Luego de trabajar casi una d\u00e9cada en mercadeo en Procter & Gamble, Alberto envisiona el poder del cambio de la era digital y decide enfocarse en desarrollar el mundo del emprendimiento en Latinoam\u00e9rica. En 2012 funda su primer start-up, gogetit.com.pa, cambiando la forma de interactuar con bienes ra\u00edces en la regi\u00f3n. Alberto, sirvi\u00f3 como VP de Mercadeo de Agora Technologies en Silicon Valley, compa\u00f1\u00eda financiada por Guy Kawasaki & Nolan Bushnell y desarroll\u00f3 el concepto global de Startup Icon. Hoy, Alberto es el CEO del holding de compa\u00f1\u00edas que conforman Latam Digital Marketing, Gogetit y sus subsidiarias en Latinoam\u00e9rica.","sameAs":["https:\/\/www.facebook.com\/Latamdigitalmarketing\/","http:\/\/linkedin.com\/in\/albertoalvarezm","https:\/\/x.com\/AgenciaLDM"],"url":"https:\/\/www.latamdigitalmarketing.com\/blog\/bio\/alberto-alvarez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/posts\/2903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/comments?post=2903"}],"version-history":[{"count":25,"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/posts\/2903\/revisions"}],"predecessor-version":[{"id":3854,"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/posts\/2903\/revisions\/3854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/media\/2934"}],"wp:attachment":[{"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/media?parent=2903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/categories?post=2903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.latamdigitalmarketing.com\/blog\/wp-json\/wp\/v2\/tags?post=2903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}